{"id":131930,"date":"2026-05-12T02:16:42","date_gmt":"2026-05-12T00:16:42","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/citykirche-alter-markt\/"},"modified":"2026-05-12T02:16:42","modified_gmt":"2026-05-12T00:16:42","slug":"citykirche-alter-markt","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/","title":{"rendered":"Citykirche Alter Markt"},"content":{"rendered":"<p>Die Citykirche Alter Markt in M\u00f6nchengladbach vereint historische Architektur mit einem modernen kulturellen Angebot. Der sp\u00e4tgotische Bau, errichtet zwischen 1469 und 1533, beeindruckt durch seinen hohen Turm, der in vier Geschosse gegliedert ist und von einem achteckigen Helm gekr\u00f6nt wird. Der dreischiffige Innenraum besticht durch seine Weite und Schlichtheit, wobei die W\u00e4nde des Mittelschiffs von f\u00fcnf starken S\u00e4ulen getragen werden, die sich in weiten Gew\u00f6lben zu den Seitenschiffen \u00f6ffnen. Eine gro\u00dfe Orgel vervollst\u00e4ndigt die Empore \u00fcber dem Hauptportal.<\/p>\n<p>Erg\u00e4nzend zur pastoralen Arbeit der Innenstadtgemeinden bietet die Citykirche ein vielf\u00e4ltiges Programm unter den Leitworten \u201eStille, Gebet, Begegnung und Kultur\u201c. Der Dialog mit Kunst und Kultur, Musik, Theater, bildender Kunst, Film und Literatur \u00f6ffnet neue Erfahrungsr\u00e4ume. Die Citykirche hat sich als Eventlocation fest in der kulturellen Szene der Stadt etabliert. In der Cityseelsorge wird ein innovatives kirchlich-religi\u00f6ses Angebot f\u00fcr Sinnsuchende und Interessierte im urbanen Milieu geschaffen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Citykirche Alter Markt in M\u00f6nchengladbach vereint historische Architektur mit einem modernen kulturellen Angebot. Der sp\u00e4tgotische Bau, errichtet zwischen 1469 und 1533, beeindruckt durch seinen hohen Turm, der in vier Geschosse gegliedert ist und von einem achteckigen Helm gekr\u00f6nt wird. Der dreischiffige Innenraum besticht durch seine Weite und Schlichtheit, wobei die W\u00e4nde des Mittelschiffs von [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":100837,"template":"","destinations":[242],"class_list":["post-131930","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-kirchen-kloester"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citykirche Alter Markt - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citykirche Alter Markt - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die Citykirche Alter Markt in M\u00f6nchengladbach vereint historische Architektur mit einem modernen kulturellen Angebot. Der sp\u00e4tgotische Bau, errichtet zwischen 1469 und 1533, beeindruckt durch seinen hohen Turm, der in vier Geschosse gegliedert ist und von einem achteckigen Helm gekr\u00f6nt wird. Der dreischiffige Innenraum besticht durch seine Weite und Schlichtheit, wobei die W\u00e4nde des Mittelschiffs von [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/citykirche-mg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/\",\"name\":\"Citykirche Alter Markt - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-12T00:16:42+00:00\",\"dateModified\":\"2026-05-12T00:16:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Citykirche Alter Markt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citykirche Alter Markt - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/","og_locale":"nl_NL","og_type":"article","og_title":"Citykirche Alter Markt - Stadt. Land. Niederrhein","og_description":"Die Citykirche Alter Markt in M\u00f6nchengladbach vereint historische Architektur mit einem modernen kulturellen Angebot. Der sp\u00e4tgotische Bau, errichtet zwischen 1469 und 1533, beeindruckt durch seinen hohen Turm, der in vier Geschosse gegliedert ist und von einem achteckigen Helm gekr\u00f6nt wird. Der dreischiffige Innenraum besticht durch seine Weite und Schlichtheit, wobei die W\u00e4nde des Mittelschiffs von [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2048,"height":1365,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/citykirche-mg.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/","name":"Citykirche Alter Markt - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-12T00:16:42+00:00","dateModified":"2026-05-12T00:16:42+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/citykirche-alter-markt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"Citykirche Alter Markt"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131930\/revisions"}],"predecessor-version":[{"id":131997,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131930\/revisions\/131997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/100837"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=131930"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=131930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}