{"id":132346,"date":"2026-09-02T01:49:46","date_gmt":"2026-09-01T23:49:46","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/quirinus-muenster\/"},"modified":"2026-09-02T01:49:46","modified_gmt":"2026-09-01T23:49:46","slug":"quirinus-muenster","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/","title":{"rendered":"Quirinus-M\u00fcnster"},"content":{"rendered":"<p>Das Quirinus-M\u00fcnster, ein markantes Wahrzeichen der Stadt Neuss, pr\u00e4gt die Stadtsilhouette seit Jahrhunderten. Die im 13. Jahrhundert errichtete Emporenbasilika geht auf die Grundsteinlegung eines Klosters im 11. Jahrhundert zur\u00fcck, das die Gebeine des Heiligen Quirinus beherbergte. Diese aus Rom \u00fcberf\u00fchrten Reliquien machten das Kloster im Mittelalter zu einem bedeutenden Pilgerziel. Der urspr\u00fcnglich etwa 100 Meter hohe Westturm fiel 1741 einem Brand zum Opfer, ebenso wie andere Geb\u00e4udeteile. Die gotischen Spitzhelme wurden nicht wieder aufgebaut, stattdessen erhielt der Ostturm eine Barockkuppel mit dem Standbild des Heiligen Quirinus. W\u00e4hrend der Franz\u00f6sischen Revolution erlitt das M\u00fcnster erhebliche Sch\u00e4den, und wertvolle sakrale Gegenst\u00e4nde gingen verloren. Im Zweiten Weltkrieg zerst\u00f6rte eine Fliegerbombe die Ostkonche, doch bis 1950 konnten die Sch\u00e4den behoben werden. Zwischen 1988 und 2006 erfolgte eine umfassende Restaurierung. 2009 verlieh Papst Benedikt XVI. der Kirche den Titel einer Basilica minor, was ihre Bedeutung f\u00fcr die Region unterstreicht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Quirinus-M\u00fcnster, ein markantes Wahrzeichen der Stadt Neuss, pr\u00e4gt die Stadtsilhouette seit Jahrhunderten. Die im 13. Jahrhundert errichtete Emporenbasilika geht auf die Grundsteinlegung eines Klosters im 11. Jahrhundert zur\u00fcck, das die Gebeine des Heiligen Quirinus beherbergte. Diese aus Rom \u00fcberf\u00fchrten Reliquien machten das Kloster im Mittelalter zu einem bedeutenden Pilgerziel. Der urspr\u00fcnglich etwa 100 Meter [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":7963,"template":"","destinations":[242],"class_list":["post-132346","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-kirchen-kloester"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quirinus-M\u00fcnster - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quirinus-M\u00fcnster - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Quirinus-M\u00fcnster, ein markantes Wahrzeichen der Stadt Neuss, pr\u00e4gt die Stadtsilhouette seit Jahrhunderten. Die im 13. Jahrhundert errichtete Emporenbasilika geht auf die Grundsteinlegung eines Klosters im 11. Jahrhundert zur\u00fcck, das die Gebeine des Heiligen Quirinus beherbergte. Diese aus Rom \u00fcberf\u00fchrten Reliquien machten das Kloster im Mittelalter zu einem bedeutenden Pilgerziel. Der urspr\u00fcnglich etwa 100 Meter [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/08\/quirinus-m-nster-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1702\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/\",\"name\":\"Quirinus-M\u00fcnster - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-09-01T23:49:46+00:00\",\"dateModified\":\"2026-09-01T23:49:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quirinus-M\u00fcnster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quirinus-M\u00fcnster - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/","og_locale":"nl_NL","og_type":"article","og_title":"Quirinus-M\u00fcnster - Stadt. Land. Niederrhein","og_description":"Das Quirinus-M\u00fcnster, ein markantes Wahrzeichen der Stadt Neuss, pr\u00e4gt die Stadtsilhouette seit Jahrhunderten. Die im 13. Jahrhundert errichtete Emporenbasilika geht auf die Grundsteinlegung eines Klosters im 11. Jahrhundert zur\u00fcck, das die Gebeine des Heiligen Quirinus beherbergte. Diese aus Rom \u00fcberf\u00fchrten Reliquien machten das Kloster im Mittelalter zu einem bedeutenden Pilgerziel. Der urspr\u00fcnglich etwa 100 Meter [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2560,"height":1702,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/08\/quirinus-m-nster-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/","name":"Quirinus-M\u00fcnster - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-09-01T23:49:46+00:00","dateModified":"2026-09-01T23:49:46+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/quirinus-muenster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"Quirinus-M\u00fcnster"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/132346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/132346\/revisions"}],"predecessor-version":[{"id":132542,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/132346\/revisions\/132542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/7963"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=132346"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=132346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}