{"id":133005,"date":"2026-09-02T01:35:22","date_gmt":"2026-09-01T23:35:22","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/pankok-museum-haus-esselt\/"},"modified":"2026-09-02T01:35:22","modified_gmt":"2026-09-01T23:35:22","slug":"pankok-museum-haus-esselt","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/","title":{"rendered":"Pankok Museum Haus Esselt"},"content":{"rendered":"<p>Otto Pankok, ein bedeutender Maler und Bildhauer des 20. Jahrhunderts, wirkte gemeinsam mit K\u00fcnstlern wie Nolde und Barlach. In seinen letzten Lebensjahren lebte er mit seiner Familie im Haus Esselt in H\u00fcnxe-Drevenack. Nach seinem Tod wurde das Pankokmuseum gegr\u00fcndet, das k\u00fcrzlich nach umfassender Restaurierung wiederer\u00f6ffnet wurde. Es bietet Einblicke in sein k\u00fcnstlerisches Schaffen und sein Leben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Otto Pankok, ein bedeutender Maler und Bildhauer des 20. Jahrhunderts, wirkte gemeinsam mit K\u00fcnstlern wie Nolde und Barlach. In seinen letzten Lebensjahren lebte er mit seiner Familie im Haus Esselt in H\u00fcnxe-Drevenack. Nach seinem Tod wurde das Pankokmuseum gegr\u00fcndet, das k\u00fcrzlich nach umfassender Restaurierung wiederer\u00f6ffnet wurde. Es bietet Einblicke in sein k\u00fcnstlerisches Schaffen und sein [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":119151,"template":"","destinations":[170],"class_list":["post-133005","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-museen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pankok Museum Haus Esselt - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pankok Museum Haus Esselt - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Otto Pankok, ein bedeutender Maler und Bildhauer des 20. Jahrhunderts, wirkte gemeinsam mit K\u00fcnstlern wie Nolde und Barlach. In seinen letzten Lebensjahren lebte er mit seiner Familie im Haus Esselt in H\u00fcnxe-Drevenack. Nach seinem Tod wurde das Pankokmuseum gegr\u00fcndet, das k\u00fcrzlich nach umfassender Restaurierung wiederer\u00f6ffnet wurde. Es bietet Einblicke in sein k\u00fcnstlerisches Schaffen und sein [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/10\/pankok-museum-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/\",\"name\":\"Pankok Museum Haus Esselt - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-09-01T23:35:22+00:00\",\"dateModified\":\"2026-09-01T23:35:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pankok Museum Haus Esselt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pankok Museum Haus Esselt - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/","og_locale":"nl_NL","og_type":"article","og_title":"Pankok Museum Haus Esselt - Stadt. Land. Niederrhein","og_description":"Otto Pankok, ein bedeutender Maler und Bildhauer des 20. Jahrhunderts, wirkte gemeinsam mit K\u00fcnstlern wie Nolde und Barlach. In seinen letzten Lebensjahren lebte er mit seiner Familie im Haus Esselt in H\u00fcnxe-Drevenack. Nach seinem Tod wurde das Pankokmuseum gegr\u00fcndet, das k\u00fcrzlich nach umfassender Restaurierung wiederer\u00f6ffnet wurde. Es bietet Einblicke in sein k\u00fcnstlerisches Schaffen und sein [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2560,"height":1920,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/10\/pankok-museum-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/","name":"Pankok Museum Haus Esselt - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-09-01T23:35:22+00:00","dateModified":"2026-09-01T23:35:22+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/pankok-museum-haus-esselt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"Pankok Museum Haus Esselt"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/133005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/133005\/revisions"}],"predecessor-version":[{"id":133245,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/133005\/revisions\/133245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/119151"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=133005"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=133005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}