{"id":133013,"date":"2026-09-02T02:03:07","date_gmt":"2026-09-02T00:03:07","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/kapelle-luehlerheim\/"},"modified":"2026-09-02T02:03:07","modified_gmt":"2026-09-02T00:03:07","slug":"kapelle-luehlerheim","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/","title":{"rendered":"Kapelle L\u00fchlerheim"},"content":{"rendered":"<p>Die Kapelle L\u00fchlerheim, seit \u00fcber einem Jahrhundert ein Ort der Besinnung, bietet Raum f\u00fcr innere Einkehr und Neuausrichtung. Sie fungiert nicht nur als Andachtsraum, sondern auch als zentraler Treffpunkt des L\u00fchlerheims. Hier finden Konzerte und Versammlungen statt, und sie ist als Hochzeitskirche gesch\u00e4tzt. Die Kapelle ist ein bedeutender Bestandteil des kulturellen Lebens in Schermbeck und bietet eine einzigartige Atmosph\u00e4re f\u00fcr vielf\u00e4ltige Veranstaltungen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Kapelle L\u00fchlerheim, seit \u00fcber einem Jahrhundert ein Ort der Besinnung, bietet Raum f\u00fcr innere Einkehr und Neuausrichtung. Sie fungiert nicht nur als Andachtsraum, sondern auch als zentraler Treffpunkt des L\u00fchlerheims. Hier finden Konzerte und Versammlungen statt, und sie ist als Hochzeitskirche gesch\u00e4tzt. Die Kapelle ist ein bedeutender Bestandteil des kulturellen Lebens in Schermbeck und [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":101118,"template":"","destinations":[242],"class_list":["post-133013","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-kirchen-kloester"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kapelle L\u00fchlerheim - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kapelle L\u00fchlerheim - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die Kapelle L\u00fchlerheim, seit \u00fcber einem Jahrhundert ein Ort der Besinnung, bietet Raum f\u00fcr innere Einkehr und Neuausrichtung. Sie fungiert nicht nur als Andachtsraum, sondern auch als zentraler Treffpunkt des L\u00fchlerheims. Hier finden Konzerte und Versammlungen statt, und sie ist als Hochzeitskirche gesch\u00e4tzt. Die Kapelle ist ein bedeutender Bestandteil des kulturellen Lebens in Schermbeck und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/kapelle-l-hlerheim.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"340\" \/>\n\t<meta property=\"og:image:height\" content=\"227\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/\",\"name\":\"Kapelle L\u00fchlerheim - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-09-02T00:03:07+00:00\",\"dateModified\":\"2026-09-02T00:03:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kapelle L\u00fchlerheim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kapelle L\u00fchlerheim - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/","og_locale":"nl_NL","og_type":"article","og_title":"Kapelle L\u00fchlerheim - Stadt. Land. Niederrhein","og_description":"Die Kapelle L\u00fchlerheim, seit \u00fcber einem Jahrhundert ein Ort der Besinnung, bietet Raum f\u00fcr innere Einkehr und Neuausrichtung. Sie fungiert nicht nur als Andachtsraum, sondern auch als zentraler Treffpunkt des L\u00fchlerheims. Hier finden Konzerte und Versammlungen statt, und sie ist als Hochzeitskirche gesch\u00e4tzt. Die Kapelle ist ein bedeutender Bestandteil des kulturellen Lebens in Schermbeck und [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":340,"height":227,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/kapelle-l-hlerheim.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/","name":"Kapelle L\u00fchlerheim - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-09-02T00:03:07+00:00","dateModified":"2026-09-02T00:03:07+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kapelle-luehlerheim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"Kapelle L\u00fchlerheim"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/133013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/133013\/revisions"}],"predecessor-version":[{"id":133180,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/133013\/revisions\/133180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/101118"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=133013"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=133013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}