{"id":134744,"date":"2026-09-02T02:03:00","date_gmt":"2026-09-02T00:03:00","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/kirche-st-peter-born\/"},"modified":"2026-09-02T02:03:00","modified_gmt":"2026-09-02T00:03:00","slug":"kirche-st-peter-born","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/","title":{"rendered":"Kirche St. Peter Born"},"content":{"rendered":"<p>Die Kirche St. Peter in Born, erstmals 1136 als einschiffige Kapelle in einer Zehntliste des K\u00f6lner Klosters St. Pantaleon erw\u00e4hnt, hat eine bewegte Baugeschichte. Mit der Erhebung zur Pfarrkirche 1433\/34 wurde der Chor angebaut, und bis 1475 erfolgten weitere bauliche Anpassungen, die das heutige Erscheinungsbild pr\u00e4gen. Der 1466\/67 errichtete Kirchturm, mit einer H\u00f6he von 31,4 Metern, wirkt im Vergleich zum Langhaus imposant. Um den gesamten Pfarrbezirk, der L\u00fcttelbracht und Genholt umfasst, mit dem Glockengel\u00e4ut zu erreichen, musste die Glocke hoch \u00fcber dem Turm erklingen. Der Turmhelm fiel 1496 und 1800 Sturmwinden zum Opfer, der 1802 neu errichtete Achteckhelm wurde in der H\u00f6he reduziert. Im Inneren der Kirche ist der sp\u00e4tromanische Traufstein aus Namurer Blaustein aus dem fr\u00fchen 13. Jahrhundert hervorzuheben. Eine Marienstatue aus der K\u00f6lner Bildschnitzerschule des 16. Jahrhunderts und eine Kanzel aus dem 17. Jahrhundert erg\u00e4nzen die historische Ausstattung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die katholische Kirche St. Peter in Born, Br\u00fcggen, ist ein religi\u00f6ser Ort im Kreis Viersen.<\/p>\n","protected":false},"author":0,"featured_media":101480,"template":"","destinations":[242],"class_list":["post-134744","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-kirchen-kloester"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kirche St. Peter Born - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kirche St. Peter Born - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die katholische Kirche St. Peter in Born, Br\u00fcggen, ist ein religi\u00f6ser Ort im Kreis Viersen.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/kirche-born.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/\",\"name\":\"Kirche St. Peter Born - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-09-02T00:03:00+00:00\",\"dateModified\":\"2026-09-02T00:03:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kirche St. Peter Born\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kirche St. Peter Born - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/","og_locale":"nl_NL","og_type":"article","og_title":"Kirche St. Peter Born - Stadt. Land. Niederrhein","og_description":"Die katholische Kirche St. Peter in Born, Br\u00fcggen, ist ein religi\u00f6ser Ort im Kreis Viersen.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2048,"height":1365,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/kirche-born.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/","name":"Kirche St. Peter Born - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-09-02T00:03:00+00:00","dateModified":"2026-09-02T00:03:00+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/kirche-st-peter-born\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"Kirche St. Peter Born"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/134744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":2,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/134744\/revisions"}],"predecessor-version":[{"id":140655,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/134744\/revisions\/140655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/101480"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=134744"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=134744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}