{"id":134867,"date":"2026-09-02T01:41:11","date_gmt":"2026-09-01T23:41:11","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/juedischer-friedhof\/"},"modified":"2026-09-02T01:41:11","modified_gmt":"2026-09-01T23:41:11","slug":"juedischer-friedhof","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/","title":{"rendered":"J\u00fcdischer Friedhof"},"content":{"rendered":"<p>Der j\u00fcdische Friedhof in Sonsbeck ist ein bedeutendes historisches Zeugnis, das erstmals 1734 erw\u00e4hnt wurde. Die urspr\u00fcngliche Begr\u00e4bnisst\u00e4tte an der Filderstra\u00dfe wurde bis etwa 1834 genutzt und ist heute nicht mehr sichtbar. Ab 1844 entstand an der Xantener Stra\u00dfe ein neuer Friedhof, der bis 1937 belegt wurde. Heute sind dort 33 Grabsteine erhalten, die \u00fcber einen Privatweg zug\u00e4nglich sind. Die j\u00fcdische Gemeinde in Sonsbeck z\u00e4hlte um 1900 etwa 40 Mitglieder. Mit der Deportation und Ermordung des Ehepaars Markus im Jahr 1943 endete das j\u00fcdische Leben in der Region. Der Friedhof ist das letzte sichtbare Zeugnis dieser Geschichte. Um das Bewusstsein f\u00fcr diese Vergangenheit zu st\u00e4rken, errichtete der Verein f\u00fcr Denkmalpflege eine Gedenkstele aus Eifeler Basaltlava. Diese tr\u00e4gt die Inschrift \u201eJ\u00fcdischer Friedhof Sonsbeck\u201c und einen Davidstern. Eine ausklappbare Tafel bietet Informationen \u00fcber die bestatteten Personen, ihre Grabsteine, Inschriften und Symbole. Das Projekt wurde mit Unterst\u00fctzung des Landes NRW und des Landesverbandes der J\u00fcdischen Gemeinden im Rheinland realisiert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der j\u00fcdische Friedhof in Sonsbeck ist ein bedeutendes historisches Zeugnis, das erstmals 1734 erw\u00e4hnt wurde. Die urspr\u00fcngliche Begr\u00e4bnisst\u00e4tte an der Filderstra\u00dfe wurde bis etwa 1834 genutzt und ist heute nicht mehr sichtbar. Ab 1844 entstand an der Xantener Stra\u00dfe ein neuer Friedhof, der bis 1937 belegt wurde. Heute sind dort 33 Grabsteine erhalten, die \u00fcber [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":110574,"template":"","destinations":[235],"class_list":["post-134867","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>J\u00fcdischer Friedhof - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J\u00fcdischer Friedhof - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Der j\u00fcdische Friedhof in Sonsbeck ist ein bedeutendes historisches Zeugnis, das erstmals 1734 erw\u00e4hnt wurde. Die urspr\u00fcngliche Begr\u00e4bnisst\u00e4tte an der Filderstra\u00dfe wurde bis etwa 1834 genutzt und ist heute nicht mehr sichtbar. Ab 1844 entstand an der Xantener Stra\u00dfe ein neuer Friedhof, der bis 1937 belegt wurde. Heute sind dort 33 Grabsteine erhalten, die \u00fcber [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/07\/sonsbeck-j-discher-friedhof-2-cc-by-sa-gemeinde-sonsbeck-nicole-wagener.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/\",\"name\":\"J\u00fcdischer Friedhof - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-09-01T23:41:11+00:00\",\"dateModified\":\"2026-09-01T23:41:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"J\u00fcdischer Friedhof\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"J\u00fcdischer Friedhof - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/","og_locale":"nl_NL","og_type":"article","og_title":"J\u00fcdischer Friedhof - Stadt. Land. Niederrhein","og_description":"Der j\u00fcdische Friedhof in Sonsbeck ist ein bedeutendes historisches Zeugnis, das erstmals 1734 erw\u00e4hnt wurde. Die urspr\u00fcngliche Begr\u00e4bnisst\u00e4tte an der Filderstra\u00dfe wurde bis etwa 1834 genutzt und ist heute nicht mehr sichtbar. Ab 1844 entstand an der Xantener Stra\u00dfe ein neuer Friedhof, der bis 1937 belegt wurde. Heute sind dort 33 Grabsteine erhalten, die \u00fcber [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1920,"height":1446,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/07\/sonsbeck-j-discher-friedhof-2-cc-by-sa-gemeinde-sonsbeck-nicole-wagener.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/","name":"J\u00fcdischer Friedhof - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-09-01T23:41:11+00:00","dateModified":"2026-09-01T23:41:11+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/juedischer-friedhof\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"J\u00fcdischer Friedhof"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/134867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/134867\/revisions"}],"predecessor-version":[{"id":135036,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/134867\/revisions\/135036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/110574"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=134867"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=134867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}