{"id":134890,"date":"2026-09-02T02:02:52","date_gmt":"2026-09-02T00:02:52","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/nikolauskloster\/"},"modified":"2026-09-02T02:02:52","modified_gmt":"2026-09-02T00:02:52","slug":"nikolauskloster","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/","title":{"rendered":"Nikolauskloster"},"content":{"rendered":"<p>Das Nikolauskloster, dessen Urspr\u00fcnge bis ins 12. Jahrhundert zur\u00fcckreichen, ist ein bedeutendes historisches und spirituelles Zentrum in J\u00fcchen. Die Franziskaner \u00fcbernahmen die Anlage im Jahr 1401, und im 17. und 18. Jahrhundert entstanden die beeindruckende vierfl\u00fcgelige Backsteinanlage und die Saalkirche mit ihren gro\u00dfen Deckengem\u00e4lden. Im 18. Jahrhundert erwarb F\u00fcrst Josef von Salm-Reifferscheidt das Kloster und lie\u00df die Kirche 1860 sanieren, um sie wieder f\u00fcr Gottesdienste zu nutzen. Seit 1904 ist das Kloster Heimat der \u201eH\u00fcnefelder Oblaten\u201c.<\/p>\n<p>Das Kloster bietet eine Vielzahl von M\u00f6glichkeiten zur Erholung und Besinnung. Der Klosterladen, die Klosterkirche und die weitl\u00e4ufige Parkanlage mit Wanderwegen, einer versteckten Mariengrotte und einem Soldatenfriedhof laden zu einem ausgiebigen Besuch ein. Das Klostercaf\u00e9 verw\u00f6hnt am Wochenende mit hausgemachter Hausmannskost und einer Kaffeetafel. F\u00fcr \u00dcbernachtungsg\u00e4ste stehen in der angegliederten Pension helle, traditionell eingerichtete Zimmer zur Verf\u00fcgung, die einen angenehmen Aufenthalt garantieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Nikolauskloster, dessen Urspr\u00fcnge bis ins 12. Jahrhundert zur\u00fcckreichen, ist ein bedeutendes historisches und spirituelles Zentrum in J\u00fcchen. Die Franziskaner \u00fcbernahmen die Anlage im Jahr 1401, und im 17. und 18. Jahrhundert entstanden die beeindruckende vierfl\u00fcgelige Backsteinanlage und die Saalkirche mit ihren gro\u00dfen Deckengem\u00e4lden. Im 18. Jahrhundert erwarb F\u00fcrst Josef von Salm-Reifferscheidt das Kloster und [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":100670,"template":"","destinations":[242],"class_list":["post-134890","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-kirchen-kloester"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nikolauskloster - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nikolauskloster - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Nikolauskloster, dessen Urspr\u00fcnge bis ins 12. Jahrhundert zur\u00fcckreichen, ist ein bedeutendes historisches und spirituelles Zentrum in J\u00fcchen. Die Franziskaner \u00fcbernahmen die Anlage im Jahr 1401, und im 17. und 18. Jahrhundert entstanden die beeindruckende vierfl\u00fcgelige Backsteinanlage und die Saalkirche mit ihren gro\u00dfen Deckengem\u00e4lden. Im 18. Jahrhundert erwarb F\u00fcrst Josef von Salm-Reifferscheidt das Kloster und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/nikolauskloster.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1732\" \/>\n\t<meta property=\"og:image:height\" content=\"1154\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/\",\"name\":\"Nikolauskloster - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-09-02T00:02:52+00:00\",\"dateModified\":\"2026-09-02T00:02:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nikolauskloster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nikolauskloster - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/","og_locale":"nl_NL","og_type":"article","og_title":"Nikolauskloster - Stadt. Land. Niederrhein","og_description":"Das Nikolauskloster, dessen Urspr\u00fcnge bis ins 12. Jahrhundert zur\u00fcckreichen, ist ein bedeutendes historisches und spirituelles Zentrum in J\u00fcchen. Die Franziskaner \u00fcbernahmen die Anlage im Jahr 1401, und im 17. und 18. Jahrhundert entstanden die beeindruckende vierfl\u00fcgelige Backsteinanlage und die Saalkirche mit ihren gro\u00dfen Deckengem\u00e4lden. Im 18. Jahrhundert erwarb F\u00fcrst Josef von Salm-Reifferscheidt das Kloster und [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1732,"height":1154,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/nikolauskloster.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/","name":"Nikolauskloster - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-09-02T00:02:52+00:00","dateModified":"2026-09-02T00:02:52+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/nikolauskloster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"Nikolauskloster"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/134890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/134890\/revisions"}],"predecessor-version":[{"id":135077,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/134890\/revisions\/135077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/100670"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=134890"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=134890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}