{"id":106393,"date":"2026-05-13T01:00:22","date_gmt":"2026-05-12T23:00:22","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/"},"modified":"2026-05-13T01:00:22","modified_gmt":"2026-05-12T23:00:22","slug":"picknick-wunderbar-bei-jedem-wetter-schoen","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/","title":{"rendered":"Picknick Wunderbar &#8211; bei jedem Wetter sch\u00f6n"},"content":{"rendered":"<p>Picknick Wunderbar bietet ein einzigartiges Picknickerlebnis am Martinsee, der exklusiv im Rahmen des Angebots zug\u00e4nglich ist. Verschiedene H\u00fctten und Picknickpl\u00e4tze stehen bereit, darunter sechs Pl\u00e4tze auf dem Plantanenhof der alten Ziegelei. Ein vorbestellter Picknickkorb und ein Transponder f\u00fcr den Zugang zum See runden das Angebot ab. Hunde sind auf dem Plantanenhof willkommen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Picknick Wunderbar bietet ein einzigartiges Picknickerlebnis am Martinsee, der exklusiv im Rahmen des Angebots zug\u00e4nglich ist. Verschiedene H\u00fctten und Picknickpl\u00e4tze stehen bereit, darunter sechs Pl\u00e4tze auf dem Plantanenhof der alten Ziegelei. Ein vorbestellter Picknickkorb und ein Transponder f\u00fcr den Zugang zum See runden das Angebot ab. Hunde sind auf dem Plantanenhof willkommen.<\/p>\n","protected":false},"author":0,"featured_media":105425,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[90],"class_list":["post-106393","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry","operating_mode-cafe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Picknick Wunderbar - bei jedem Wetter sch\u00f6n - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Picknick Wunderbar - bei jedem Wetter sch\u00f6n - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Picknick Wunderbar bietet ein einzigartiges Picknickerlebnis am Martinsee, der exklusiv im Rahmen des Angebots zug\u00e4nglich ist. Verschiedene H\u00fctten und Picknickpl\u00e4tze stehen bereit, darunter sechs Pl\u00e4tze auf dem Plantanenhof der alten Ziegelei. Ein vorbestellter Picknickkorb und ein Transponder f\u00fcr den Zugang zum See runden das Angebot ab. Hunde sind auf dem Plantanenhof willkommen.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/04\/blick-auf-den-martinsee.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1020\" \/>\n\t<meta property=\"og:image:height\" content=\"765\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/\",\"name\":\"Picknick Wunderbar - bei jedem Wetter sch\u00f6n - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-12T23:00:22+00:00\",\"dateModified\":\"2026-05-12T23:00:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinair\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/culinair\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Picknick Wunderbar - bei jedem Wetter sch\u00f6n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Picknick Wunderbar - bei jedem Wetter sch\u00f6n - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/","og_locale":"nl_NL","og_type":"article","og_title":"Picknick Wunderbar - bei jedem Wetter sch\u00f6n - Stadt. Land. Niederrhein","og_description":"Picknick Wunderbar bietet ein einzigartiges Picknickerlebnis am Martinsee, der exklusiv im Rahmen des Angebots zug\u00e4nglich ist. Verschiedene H\u00fctten und Picknickpl\u00e4tze stehen bereit, darunter sechs Pl\u00e4tze auf dem Plantanenhof der alten Ziegelei. Ein vorbestellter Picknickkorb und ein Transponder f\u00fcr den Zugang zum See runden das Angebot ab. Hunde sind auf dem Plantanenhof willkommen.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1020,"height":765,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/04\/blick-auf-den-martinsee.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/","name":"Picknick Wunderbar - bei jedem Wetter sch\u00f6n - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-12T23:00:22+00:00","dateModified":"2026-05-12T23:00:22+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/picknick-wunderbar-bei-jedem-wetter-schoen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Culinair","item":"https:\/\/stadt-land-niederrhein.de\/nl\/culinair\/"},{"@type":"ListItem","position":3,"name":"Picknick Wunderbar - bei jedem Wetter sch\u00f6n"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/106393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":3,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/106393\/revisions"}],"predecessor-version":[{"id":123451,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/106393\/revisions\/123451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/105425"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=106393"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/cuisines?post=106393"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/features?post=106393"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/kitchen_offers?post=106393"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/operating_modes?post=106393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}