{"id":109006,"date":"2026-05-11T03:06:31","date_gmt":"2026-05-11T01:06:31","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/biobaeckerei-schomaker-2\/"},"modified":"2026-05-11T03:06:31","modified_gmt":"2026-05-11T01:06:31","slug":"biobaeckerei-schomaker-2","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/","title":{"rendered":"Biob\u00e4ckerei Schomaker"},"content":{"rendered":"<p>Die Biob\u00e4ckerei Schomaker in Neukirchen-Vluyn verarbeitet Sommerweizen vom Biolandhof Frohnenbruch zu Brot und Backwaren. B\u00e4ckermeister Andreas Schomaker legt Wert auf \u00f6kologische Kriterien und transparente Rohstoffherkunft. Die B\u00e4ckerei wurde in einer bestehenden Halle \u00f6kologisch renoviert. Im Biostrot II werden neben Brot und Geb\u00e4ck auch Kuchen und wechselnde Tagesgerichte angeboten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Biob\u00e4ckerei Schomaker in Neukirchen-Vluyn verarbeitet Sommerweizen vom Biolandhof Frohnenbruch zu Brot und Backwaren. B\u00e4ckermeister Andreas Schomaker legt Wert auf \u00f6kologische Kriterien und transparente Rohstoffherkunft. Die B\u00e4ckerei wurde in einer bestehenden Halle \u00f6kologisch renoviert. Im Biostrot II werden neben Brot und Geb\u00e4ck auch Kuchen und wechselnde Tagesgerichte angeboten.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[90],"class_list":["post-109006","restaurant","type-restaurant","status-publish","hentry","operating_mode-cafe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biob\u00e4ckerei Schomaker - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biob\u00e4ckerei Schomaker - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die Biob\u00e4ckerei Schomaker in Neukirchen-Vluyn verarbeitet Sommerweizen vom Biolandhof Frohnenbruch zu Brot und Backwaren. B\u00e4ckermeister Andreas Schomaker legt Wert auf \u00f6kologische Kriterien und transparente Rohstoffherkunft. Die B\u00e4ckerei wurde in einer bestehenden Halle \u00f6kologisch renoviert. Im Biostrot II werden neben Brot und Geb\u00e4ck auch Kuchen und wechselnde Tagesgerichte angeboten.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/\",\"name\":\"Biob\u00e4ckerei Schomaker - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-11T01:06:31+00:00\",\"dateModified\":\"2026-05-11T01:06:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinair\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/culinair\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Biob\u00e4ckerei Schomaker\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biob\u00e4ckerei Schomaker - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/","og_locale":"nl_NL","og_type":"article","og_title":"Biob\u00e4ckerei Schomaker - Stadt. Land. Niederrhein","og_description":"Die Biob\u00e4ckerei Schomaker in Neukirchen-Vluyn verarbeitet Sommerweizen vom Biolandhof Frohnenbruch zu Brot und Backwaren. B\u00e4ckermeister Andreas Schomaker legt Wert auf \u00f6kologische Kriterien und transparente Rohstoffherkunft. Die B\u00e4ckerei wurde in einer bestehenden Halle \u00f6kologisch renoviert. Im Biostrot II werden neben Brot und Geb\u00e4ck auch Kuchen und wechselnde Tagesgerichte angeboten.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/","name":"Biob\u00e4ckerei Schomaker - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-11T01:06:31+00:00","dateModified":"2026-05-11T01:06:31+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/biobaeckerei-schomaker-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Culinair","item":"https:\/\/stadt-land-niederrhein.de\/nl\/culinair\/"},{"@type":"ListItem","position":3,"name":"Biob\u00e4ckerei Schomaker"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/109006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":3,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/109006\/revisions"}],"predecessor-version":[{"id":124146,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/109006\/revisions\/124146"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=109006"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/cuisines?post=109006"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/features?post=109006"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/kitchen_offers?post=109006"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/operating_modes?post=109006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}