{"id":116585,"date":"2026-05-11T03:13:08","date_gmt":"2026-05-11T01:13:08","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/la-fontana-gelateria\/"},"modified":"2026-05-11T03:13:08","modified_gmt":"2026-05-11T01:13:08","slug":"la-fontana-gelateria","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/","title":{"rendered":"La Fontana \/ Gelateria"},"content":{"rendered":"<p>La Fontana in Schermbeck ist eine Eisdiele, die mit einer breiten Auswahl an hausgemachten Eissorten \u00fcberzeugt. Die Lage im Herzen von Schermbeck bietet eine angenehme Atmosph\u00e4re f\u00fcr eine entspannte Pause. Die Speisekarte umfasst neben klassischen Eissorten auch kreative Variationen, die regelm\u00e4\u00dfig wechseln.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fontana in Schermbeck ist eine Eisdiele, die mit einer breiten Auswahl an hausgemachten Eissorten \u00fcberzeugt. Die Lage im Herzen von Schermbeck bietet eine angenehme Atmosph\u00e4re f\u00fcr eine entspannte Pause. Die Speisekarte umfasst neben klassischen Eissorten auch kreative Variationen, die regelm\u00e4\u00dfig wechseln.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[90],"class_list":["post-116585","restaurant","type-restaurant","status-publish","hentry","operating_mode-cafe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Fontana \/ Gelateria - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fontana \/ Gelateria - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"La Fontana in Schermbeck ist eine Eisdiele, die mit einer breiten Auswahl an hausgemachten Eissorten \u00fcberzeugt. Die Lage im Herzen von Schermbeck bietet eine angenehme Atmosph\u00e4re f\u00fcr eine entspannte Pause. Die Speisekarte umfasst neben klassischen Eissorten auch kreative Variationen, die regelm\u00e4\u00dfig wechseln.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/\",\"name\":\"La Fontana \/ Gelateria - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-11T01:13:08+00:00\",\"dateModified\":\"2026-05-11T01:13:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinair\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/culinair\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La Fontana \/ Gelateria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fontana \/ Gelateria - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/","og_locale":"nl_NL","og_type":"article","og_title":"La Fontana \/ Gelateria - Stadt. Land. Niederrhein","og_description":"La Fontana in Schermbeck ist eine Eisdiele, die mit einer breiten Auswahl an hausgemachten Eissorten \u00fcberzeugt. Die Lage im Herzen von Schermbeck bietet eine angenehme Atmosph\u00e4re f\u00fcr eine entspannte Pause. Die Speisekarte umfasst neben klassischen Eissorten auch kreative Variationen, die regelm\u00e4\u00dfig wechseln.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/","name":"La Fontana \/ Gelateria - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-11T01:13:08+00:00","dateModified":"2026-05-11T01:13:08+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/la-fontana-gelateria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Culinair","item":"https:\/\/stadt-land-niederrhein.de\/nl\/culinair\/"},{"@type":"ListItem","position":3,"name":"La Fontana \/ Gelateria"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/116585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":2,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/116585\/revisions"}],"predecessor-version":[{"id":122620,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/116585\/revisions\/122620"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=116585"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/cuisines?post=116585"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/features?post=116585"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/kitchen_offers?post=116585"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/operating_modes?post=116585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}