{"id":119911,"date":"2026-05-12T02:29:04","date_gmt":"2026-05-12T00:29:04","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/eiscafe-monego\/"},"modified":"2026-05-12T02:29:04","modified_gmt":"2026-05-12T00:29:04","slug":"eiscafe-monego","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/","title":{"rendered":"Eiscafe Monego"},"content":{"rendered":"<p>Das Eiscafe Monego in Krefeld bietet eine breite Auswahl an hausgemachten Eisspezialit\u00e4ten. Die Eisdiele ist bekannt f\u00fcr ihre kreativen Sorten, die regelm\u00e4\u00dfig wechseln und saisonale Zutaten einbeziehen. Die Lage in der Stadt erm\u00f6glicht einen entspannten Besuch, um die Vielfalt der Eiskreationen zu genie\u00dfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Eiscafe Monego in Krefeld bietet eine breite Auswahl an hausgemachten Eisspezialit\u00e4ten. Die Eisdiele ist bekannt f\u00fcr ihre kreativen Sorten, die regelm\u00e4\u00dfig wechseln und saisonale Zutaten einbeziehen. Die Lage in der Stadt erm\u00f6glicht einen entspannten Besuch, um die Vielfalt der Eiskreationen zu genie\u00dfen.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[90],"class_list":["post-119911","restaurant","type-restaurant","status-publish","hentry","operating_mode-cafe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eiscafe Monego - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eiscafe Monego - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Eiscafe Monego in Krefeld bietet eine breite Auswahl an hausgemachten Eisspezialit\u00e4ten. Die Eisdiele ist bekannt f\u00fcr ihre kreativen Sorten, die regelm\u00e4\u00dfig wechseln und saisonale Zutaten einbeziehen. Die Lage in der Stadt erm\u00f6glicht einen entspannten Besuch, um die Vielfalt der Eiskreationen zu genie\u00dfen.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/\",\"name\":\"Eiscafe Monego - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-12T00:29:04+00:00\",\"dateModified\":\"2026-05-12T00:29:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinair\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/culinair\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eiscafe Monego\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eiscafe Monego - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/","og_locale":"nl_NL","og_type":"article","og_title":"Eiscafe Monego - Stadt. Land. Niederrhein","og_description":"Das Eiscafe Monego in Krefeld bietet eine breite Auswahl an hausgemachten Eisspezialit\u00e4ten. Die Eisdiele ist bekannt f\u00fcr ihre kreativen Sorten, die regelm\u00e4\u00dfig wechseln und saisonale Zutaten einbeziehen. Die Lage in der Stadt erm\u00f6glicht einen entspannten Besuch, um die Vielfalt der Eiskreationen zu genie\u00dfen.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/","name":"Eiscafe Monego - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-12T00:29:04+00:00","dateModified":"2026-05-12T00:29:04+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/eiscafe-monego\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Culinair","item":"https:\/\/stadt-land-niederrhein.de\/nl\/culinair\/"},{"@type":"ListItem","position":3,"name":"Eiscafe Monego"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/119911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":2,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/119911\/revisions"}],"predecessor-version":[{"id":122429,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/119911\/revisions\/122429"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=119911"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/cuisines?post=119911"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/features?post=119911"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/kitchen_offers?post=119911"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/operating_modes?post=119911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}