{"id":119912,"date":"2026-09-01T02:42:06","date_gmt":"2026-09-01T00:42:06","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/glycklich-eismanufaktur\/"},"modified":"2026-09-01T02:42:06","modified_gmt":"2026-09-01T00:42:06","slug":"glycklich-eismanufaktur","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/","title":{"rendered":"glycklich Eismanufaktur"},"content":{"rendered":"<p>Die glycklich Eismanufaktur in Krefeld ist eine Eisdiele, die sich auf handwerklich hergestelltes Speiseeis spezialisiert hat. In zentraler Lage bietet sie eine breite Palette an kreativen Eissorten, die aus hochwertigen Zutaten gefertigt werden. Die Manufaktur legt Wert auf Qualit\u00e4t und Innovation, was sich in den wechselnden Sorten widerspiegelt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die glycklich Eismanufaktur in Krefeld ist eine Eisdiele, die sich auf handwerklich hergestelltes Speiseeis spezialisiert hat. In zentraler Lage bietet sie eine breite Palette an kreativen Eissorten, die aus hochwertigen Zutaten gefertigt werden. Die Manufaktur legt Wert auf Qualit\u00e4t und Innovation, was sich in den wechselnden Sorten widerspiegelt.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[90],"class_list":["post-119912","restaurant","type-restaurant","status-publish","hentry","operating_mode-cafe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>glycklich Eismanufaktur - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"glycklich Eismanufaktur - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die glycklich Eismanufaktur in Krefeld ist eine Eisdiele, die sich auf handwerklich hergestelltes Speiseeis spezialisiert hat. In zentraler Lage bietet sie eine breite Palette an kreativen Eissorten, die aus hochwertigen Zutaten gefertigt werden. Die Manufaktur legt Wert auf Qualit\u00e4t und Innovation, was sich in den wechselnden Sorten widerspiegelt.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/\",\"name\":\"glycklich Eismanufaktur - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-09-01T00:42:06+00:00\",\"dateModified\":\"2026-09-01T00:42:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinair\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/culinair\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"glycklich Eismanufaktur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"glycklich Eismanufaktur - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/","og_locale":"nl_NL","og_type":"article","og_title":"glycklich Eismanufaktur - Stadt. Land. Niederrhein","og_description":"Die glycklich Eismanufaktur in Krefeld ist eine Eisdiele, die sich auf handwerklich hergestelltes Speiseeis spezialisiert hat. In zentraler Lage bietet sie eine breite Palette an kreativen Eissorten, die aus hochwertigen Zutaten gefertigt werden. Die Manufaktur legt Wert auf Qualit\u00e4t und Innovation, was sich in den wechselnden Sorten widerspiegelt.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/","name":"glycklich Eismanufaktur - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-09-01T00:42:06+00:00","dateModified":"2026-09-01T00:42:06+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/glycklich-eismanufaktur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Culinair","item":"https:\/\/stadt-land-niederrhein.de\/nl\/culinair\/"},{"@type":"ListItem","position":3,"name":"glycklich Eismanufaktur"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/119912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":2,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/119912\/revisions"}],"predecessor-version":[{"id":122430,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/119912\/revisions\/122430"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=119912"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/cuisines?post=119912"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/features?post=119912"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/kitchen_offers?post=119912"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/operating_modes?post=119912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}