{"id":135829,"date":"2026-09-02T01:09:07","date_gmt":"2026-09-01T23:09:07","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/gaststaette-overkaemping-schult\/"},"modified":"2026-09-02T01:09:07","modified_gmt":"2026-09-01T23:09:07","slug":"gaststaette-overkaemping-schult","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/","title":{"rendered":"Gastst\u00e4tte Overk\u00e4mping-Schult"},"content":{"rendered":"<p>Die Gastst\u00e4tte Overk\u00e4mping-Schult in Schermbeck ist ein traditionsreiches Restaurant, das seit \u00fcber einem Jahrhundert das Zentrum des Dorflebens bildet. Gelegen an der Mittelstra\u00dfe, wird die Gastst\u00e4tte seit 1906 von vier Generationen von Frauen gef\u00fchrt. Die Kegelbahn ist ein beliebter Treffpunkt f\u00fcr Kegelclubs, w\u00e4hrend der Cateringservice Veranstaltungen im gesamten Gemeindegebiet unterst\u00fctzt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Gastst\u00e4tte Overk\u00e4mping-Schult in Schermbeck ist ein traditionsreiches Restaurant, das seit \u00fcber einem Jahrhundert das Zentrum des Dorflebens bildet. Gelegen an der Mittelstra\u00dfe, wird die Gastst\u00e4tte seit 1906 von vier Generationen von Frauen gef\u00fchrt. Die Kegelbahn ist ein beliebter Treffpunkt f\u00fcr Kegelclubs, w\u00e4hrend der Cateringservice Veranstaltungen im gesamten Gemeindegebiet unterst\u00fctzt.<\/p>\n","protected":false},"author":0,"featured_media":105654,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[244,92],"class_list":["post-135829","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry","operating_mode-gaststaetten","operating_mode-restaurant"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gastst\u00e4tte Overk\u00e4mping-Schult - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gastst\u00e4tte Overk\u00e4mping-Schult - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die Gastst\u00e4tte Overk\u00e4mping-Schult in Schermbeck ist ein traditionsreiches Restaurant, das seit \u00fcber einem Jahrhundert das Zentrum des Dorflebens bildet. Gelegen an der Mittelstra\u00dfe, wird die Gastst\u00e4tte seit 1906 von vier Generationen von Frauen gef\u00fchrt. Die Kegelbahn ist ein beliebter Treffpunkt f\u00fcr Kegelclubs, w\u00e4hrend der Cateringservice Veranstaltungen im gesamten Gemeindegebiet unterst\u00fctzt.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/04\/gastst-tte-overk-mping-schult.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/\",\"name\":\"Gastst\u00e4tte Overk\u00e4mping-Schult - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-09-01T23:09:07+00:00\",\"dateModified\":\"2026-09-01T23:09:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinair\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/culinair\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gastst\u00e4tte Overk\u00e4mping-Schult\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gastst\u00e4tte Overk\u00e4mping-Schult - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/","og_locale":"nl_NL","og_type":"article","og_title":"Gastst\u00e4tte Overk\u00e4mping-Schult - Stadt. Land. Niederrhein","og_description":"Die Gastst\u00e4tte Overk\u00e4mping-Schult in Schermbeck ist ein traditionsreiches Restaurant, das seit \u00fcber einem Jahrhundert das Zentrum des Dorflebens bildet. Gelegen an der Mittelstra\u00dfe, wird die Gastst\u00e4tte seit 1906 von vier Generationen von Frauen gef\u00fchrt. Die Kegelbahn ist ein beliebter Treffpunkt f\u00fcr Kegelclubs, w\u00e4hrend der Cateringservice Veranstaltungen im gesamten Gemeindegebiet unterst\u00fctzt.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2016,"height":1512,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/04\/gastst-tte-overk-mping-schult.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/","name":"Gastst\u00e4tte Overk\u00e4mping-Schult - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-09-01T23:09:07+00:00","dateModified":"2026-09-01T23:09:07+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kulinarik\/gaststaette-overkaemping-schult\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Culinair","item":"https:\/\/stadt-land-niederrhein.de\/nl\/culinair\/"},{"@type":"ListItem","position":3,"name":"Gastst\u00e4tte Overk\u00e4mping-Schult"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/135829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/135829\/revisions"}],"predecessor-version":[{"id":136048,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/restaurants\/135829\/revisions\/136048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/105654"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=135829"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/cuisines?post=135829"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/features?post=135829"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/kitchen_offers?post=135829"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/operating_modes?post=135829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}